{"id":2274,"date":"2014-06-02T14:13:42","date_gmt":"2014-06-02T14:13:42","guid":{"rendered":"http:\/\/girovai2.wandcclients.com\/it\/programs\/crociere-in-offerta\/"},"modified":"2016-07-26T14:46:37","modified_gmt":"2016-07-26T14:46:37","slug":"crociere","status":"publish","type":"page","link":"https:\/\/girovai.com\/it\/programs\/crociere\/","title":{"rendered":"Crociere"},"content":{"rendered":"<style type=\"text\/css\">a.eg-henryharrison-element-1,a.eg-henryharrison-element-2{-webkit-transition:all .4s linear;   -moz-transition:all .4s linear;   -o-transition:all .4s linear;   -ms-transition:all .4s linear;   transition:all .4s linear}.eg-jimmy-carter-element-11 i:before{margin-left:0px; margin-right:0px}.eg-harding-element-17{letter-spacing:1px}.eg-harding-wrapper .esg-entry-media{overflow:hidden; box-sizing:border-box;   -webkit-box-sizing:border-box;   -moz-box-sizing:border-box;   padding:30px 30px 0px 30px}.eg-harding-wrapper .esg-media-poster{overflow:hidden; border-radius:50%;   -webkit-border-radius:50%;   -moz-border-radius:50%}.eg-ulysses-s-grant-wrapper .esg-entry-media{overflow:hidden; box-sizing:border-box;   -webkit-box-sizing:border-box;   -moz-box-sizing:border-box;   padding:30px 30px 0px 30px}.eg-ulysses-s-grant-wrapper .esg-media-poster{overflow:hidden; border-radius:50%;   -webkit-border-radius:50%;   -moz-border-radius:50%}.eg-richard-nixon-wrapper .esg-entry-media{overflow:hidden; box-sizing:border-box;   -webkit-box-sizing:border-box;   -moz-box-sizing:border-box;   padding:30px 30px 0px 30px}.eg-richard-nixon-wrapper .esg-media-poster{overflow:hidden; border-radius:50%;   -webkit-border-radius:50%;   -moz-border-radius:50%}.eg-herbert-hoover-wrapper:hover .esg-media-poster{filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");   filter:gray;   -webkit-filter:grayscale(100%)}.eg-herbert-hoover-wrapper .esg-media-poster{filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='1 0 0 0 0,0 1 0 0 0,0 0 1 0 0,0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");  -webkit-filter:grayscale(0%)}.eg-lyndon-johnson-wrapper .esg-media-poster{filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");   filter:gray;   -webkit-filter:grayscale(100%)}.eg-lyndon-johnson-wrapper:hover .esg-media-poster{filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='1 0 0 0 0,0 1 0 0 0,0 0 1 0 0,0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");  -webkit-filter:grayscale(0%)}.esg-overlay.eg-ronald-reagan-container{background:-moz-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-webkit-gradient(linear,left top,left bottom,color-stop(50%,rgba(0,0,0,0)),color-stop(99%,rgba(0,0,0,0.83)),color-stop(100%,rgba(0,0,0,0.85))); background:-webkit-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-o-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-ms-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:linear-gradient(to bottom,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); filter:progid:DXImageTransform.Microsoft.gradient( startColorstr='#00000000',endColorstr='#d9000000',GradientType=0 )}.eg-georgebush-wrapper .esg-entry-cover{background:-moz-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-webkit-gradient(linear,left top,left bottom,color-stop(50%,rgba(0,0,0,0)),color-stop(99%,rgba(0,0,0,0.83)),color-stop(100%,rgba(0,0,0,0.85))); background:-webkit-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-o-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-ms-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:linear-gradient(to bottom,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); filter:progid:DXImageTransform.Microsoft.gradient( startColorstr='#00000000',endColorstr='#d9000000',GradientType=0 )}.eg-jefferson-wrapper{-webkit-border-radius:5px !important; -moz-border-radius:5px !important; border-radius:5px !important; -webkit-mask-image:url(data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABCAIAAACQd1PeAAAAGXRFWHRTb2Z0d2FyZQBBZG9iZSBJbWFnZVJlYWR5ccllPAAAAA5JREFUeNpiYGBgAAgwAAAEAAGbA+oJAAAAAElFTkSuQmCC) !important}.eg-monroe-element-1{text-shadow:0px 1px 3px rgba(0,0,0,0.1)}.eg-lyndon-johnson-wrapper .esg-entry-cover{background:-moz-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:-webkit-gradient(radial,center center,0px,center center,100%,color-stop(0%,rgba(0,0,0,0.35)),color-stop(96%,rgba(18,18,18,0)),color-stop(100%,rgba(19,19,19,0))); background:-webkit-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:-o-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:-ms-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:radial-gradient(ellipse at center,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); filter:progid:DXImageTransform.Microsoft.gradient( startColorstr='#59000000',endColorstr='#00131313',GradientType=1 )}.eg-wilbert-wrapper .esg-entry-cover{background:-moz-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:-webkit-gradient(radial,center center,0px,center center,100%,color-stop(0%,rgba(0,0,0,0.35)),color-stop(96%,rgba(18,18,18,0)),color-stop(100%,rgba(19,19,19,0))); background:-webkit-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:-o-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:-ms-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:radial-gradient(ellipse at center,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); filter:progid:DXImageTransform.Microsoft.gradient( startColorstr='#59000000',endColorstr='#00131313',GradientType=1 )}.eg-wilbert-wrapper .esg-media-poster{-webkit-transition:0.4s ease-in-out;  -moz-transition:0.4s ease-in-out;  -o-transition:0.4s ease-in-out;  transition:0.4s ease-in-out;  filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");   filter:gray;   -webkit-filter:grayscale(100%)}.eg-wilbert-wrapper:hover .esg-media-poster{filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='1 0 0 0 0,0 1 0 0 0,0 0 1 0 0,0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");  -webkit-filter:grayscale(0%)}.eg-phillie-element-3:after{content:\" \";width:0px;height:0px;border-style:solid;border-width:5px 5px 0 5px;border-color:#000 transparent transparent transparent;left:50%;margin-left:-5px; bottom:-5px; position:absolute}.eg-howardtaft-wrapper .esg-media-poster,.eg-howardtaft-wrapper .esg-media-poster{filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='1 0 0 0 0,0 1 0 0 0,0 0 1 0 0,0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");  -webkit-filter:grayscale(0%)}.eg-howardtaft-wrapper:hover .esg-media-poster,.eg-howardtaft-wrapper:hover .esg-media-poster{filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");   filter:gray;   -webkit-filter:grayscale(100%)}.myportfolio-container .added_to_cart.wc-forward{font-family:\"Open Sans\"; font-size:13px; color:#fff; margin-top:10px}.esgbox-title.esgbox-title-outside-wrap{font-size:15px; font-weight:700; text-align:center}.esgbox-title.esgbox-title-inside-wrap{padding-bottom:10px; font-size:15px; font-weight:700; text-align:center}.esg-content.eg-twitterstream-element-33-a{display:inline-block}.eg-twitterstream-element-35{word-break:break-all}.esg-overlay.eg-twitterstream-container{background:-moz-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-webkit-gradient(linear,left top,left bottom,color-stop(50%,rgba(0,0,0,0)),color-stop(99%,rgba(0,0,0,0.83)),color-stop(100%,rgba(0,0,0,0.85))); background:-webkit-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-o-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-ms-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:linear-gradient(to bottom,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); filter:progid:DXImageTransform.Microsoft.gradient( startColorstr='#00000000',endColorstr='#d9000000',GradientType=0 )}.esg-content.eg-facebookstream-element-33-a{display:inline-block}.eg-facebookstream-element-0{word-break:break-all}.esg-overlay.eg-flickrstream-container{background:-moz-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-webkit-gradient(linear,left top,left bottom,color-stop(50%,rgba(0,0,0,0)),color-stop(99%,rgba(0,0,0,0.83)),color-stop(100%,rgba(0,0,0,0.85))); background:-webkit-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-o-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-ms-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:linear-gradient(to bottom,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); filter:progid:DXImageTransform.Microsoft.gradient( startColorstr='#00000000',endColorstr='#d9000000',GradientType=0 )}<\/style>\n<!-- CACHE CREATED FOR: 11 --><style type=\"text\/css\">.minimal-light .navigationbuttons,.minimal-light .esg-pagination,.minimal-light .esg-filters{text-align:center}.minimal-light .esg-filterbutton,.minimal-light .esg-navigationbutton,.minimal-light .esg-sortbutton,.minimal-light .esg-cartbutton a{color:#999; margin-right:5px; cursor:pointer; padding:0px 16px; border:1px solid #e5e5e5; line-height:38px; border-radius:5px; -moz-border-radius:5px; -webkit-border-radius:5px; font-size:12px; font-weight:700; font-family:\"Open Sans\",sans-serif; display:inline-block; background:#fff; margin-bottom:5px}.minimal-light .esg-navigationbutton *{color:#999}.minimal-light .esg-navigationbutton{padding:0px 16px}.minimal-light .esg-pagination-button:last-child{margin-right:0}.minimal-light .esg-left,.minimal-light .esg-right{padding:0px 11px}.minimal-light .esg-sortbutton-wrapper,.minimal-light .esg-cartbutton-wrapper{display:inline-block}.minimal-light .esg-sortbutton-order,.minimal-light .esg-cartbutton-order{display:inline-block;  vertical-align:top;  border:1px solid #e5e5e5;  width:40px;  line-height:38px;  border-radius:0px 5px 5px 0px;  -moz-border-radius:0px 5px 5px 0px;  -webkit-border-radius:0px 5px 5px 0px;  font-size:12px;  font-weight:700;  color:#999;  cursor:pointer;  background:#fff}.minimal-light .esg-cartbutton{color:#333; cursor:default !important}.minimal-light .esg-cartbutton .esgicon-basket{color:#333;   font-size:15px;   line-height:15px;   margin-right:10px}.minimal-light .esg-cartbutton-wrapper{cursor:default !important}.minimal-light .esg-sortbutton,.minimal-light .esg-cartbutton{display:inline-block; position:relative; cursor:pointer; margin-right:0px; border-right:none; border-radius:5px 0px 0px 5px; -moz-border-radius:5px 0px 0px 5px; -webkit-border-radius:5px 0px 0px 5px}.minimal-light .esg-navigationbutton:hover,.minimal-light .esg-filterbutton:hover,.minimal-light .esg-sortbutton:hover,.minimal-light .esg-sortbutton-order:hover,.minimal-light .esg-cartbutton a:hover,.minimal-light .esg-filterbutton.selected{background-color:#fff;   border-color:#bbb;   color:#333;   box-shadow:0px 3px 5px 0px rgba(0,0,0,0.13)}.minimal-light .esg-navigationbutton:hover *{color:#333}.minimal-light .esg-sortbutton-order.tp-desc:hover{border-color:#bbb; color:#333; box-shadow:0px -3px 5px 0px rgba(0,0,0,0.13) !important}.minimal-light .esg-filter-checked{padding:1px 3px;  color:#cbcbcb;  background:#cbcbcb;  margin-left:7px;  font-size:9px;  font-weight:300;  line-height:9px;  vertical-align:middle}.minimal-light .esg-filterbutton.selected .esg-filter-checked,.minimal-light .esg-filterbutton:hover .esg-filter-checked{padding:1px 3px 1px 3px;  color:#fff;  background:#000;  margin-left:7px;  font-size:9px;  font-weight:300;  line-height:9px;  vertical-align:middle}.minimal-light .esg-filterbutton{color:#999 !important}.minimal-light .esg-selected-filterbutton{border:1px solid #E5E5E5;background:#fff; padding:10px 20px 10px 30px; color:#999; border-radius:4px;font-weight:700}.minimal-light .esg-selected-filterbutton .eg-icon-down-open{margin-left:5px;font-size:12px; line-height:20px; vertical-align:top; color:#999}.minimal-light .esg-filter-wrapper .esg-filterbutton span i{color:#fff !important}.minimal-light .esg-filter-wrapper .esg-filterbutton:hover span,.minimal-light .esg-filter-wrapper .esg-filterbutton.selected span{color:#000 !important}.minimal-light .esg-filter-wrapper .esg-filterbutton:hover span i,.minimal-light .esg-filter-wrapper .esg-filterbutton.selected span i{color:#fff !important}.minimal-light .esg-selected-filterbutton:hover .eg-icon-down-open,.minimal-light .esg-selected-filterbutton.hoveredfilter .eg-icon-down-open{color:rgba(0,0,0,1) !important}.minimal-light .esg-cartbutton:hover,.minimal-light .esg-selected-filterbutton:hover,.minimal-light .esg-selected-filterbutton.hoveredfilter{border-color:#bbb; color:#333; box-shadow:0px 3px 5px 0px rgba(0,0,0,0.13)}.minimal-light .esg-dropdown-wrapper{background:#fff; border-radius:5px;-moz-border-radius:5px;-webkit-border-radius:5px; border:1px solid #bbb; box-shadow:0px 3px 5px 0px rgba(0,0,0,0.13)}.minimal-light .esg-dropdown-wrapper .esg-filterbutton{border:none !important;line-height:25px; white-space:nowrap; padding:0px 10px; font-weight:700; text-align:left; color:#999}.minimal-light .esg-dropdown-wrapper .esg-filterbutton:hover,.minimal-light .esg-dropdown-wrapper .esg-filterbutton.selected{background:transparent !important; color:#000 !important; box-shadow:none !important}.minimal-light .esg-dropdown-wrapper .esg-filter-checked{display:inline-block; margin-left:0px !important;margin-right:7px; margin-top:-2px !important; line-height:15px !important}.minimal-light .esg-dropdown-wrapper .esg-filter-checked span{vertical-align:middle; line-height:20px}<\/style>\n<style type=\"text\/css\">.eg-girovai2-element-1{font-size:17px; line-height:18px; color:#ffffff; font-weight:800; padding:5px 5px 5px 5px ; border-radius:0px 0px 0px 0px ; background:rgba(10,10,10,0.44); z-index:2 !important; display:block; font-family:\"Bitter\"}.eg-girovai2-element-14{font-size:16px !important; line-height:22px !important; color:#ffffff !important; font-weight:400 !important; padding:17px 17px 17px 17px !important; border-radius:50% 50% 50% 50% !important; background:rgba(0,93,170,0.65) !important; z-index:2 !important; display:block; border-top-width:0px !important; border-right-width:0px !important; border-bottom-width:0px !important; border-left-width:0px !important; border-color:#ffffff !important; border-style:solid !important}.eg-girovai2-element-7{font-size:15px; line-height:18px; color:#777777; font-weight:400; display:block; text-align:center; clear:none; margin:0px 0px 0px 0px ; padding:10px 20px 0px 20px ; border-radius:0px 0px 0px 0px ; background:transparent; position:relative; z-index:2 !important; font-family:\"Open Sans\"; text-transform:capitalize; border-top-width:0px; border-right-width:0px; border-bottom-width:0px; border-left-width:0px; border-color:#e5e5e5; border-style:solid}.eg-girovai2-element-19{font-size:15px; line-height:18px; color:#777777; font-weight:400; display:block; text-align:center; clear:none; margin:0px 0px 0px 0px ; padding:10px 20px 0px 20px ; border-radius:0px 0px 0px 0px ; background:transparent; position:relative; z-index:2 !important; font-family:\"Open Sans\"; text-transform:capitalize; border-top-width:0px; border-right-width:0px; border-bottom-width:0px; border-left-width:0px; border-color:#e5e5e5; border-style:solid}.eg-girovai2-element-17{font-size:18px; line-height:18px; color:#41a320; font-weight:400; display:block; text-align:center; clear:none; margin:0px 0px 0px 0px ; padding:10px 20px 0px 20px ; border-radius:0px 0px 0px 0px ; background:transparent; position:relative; z-index:2 !important; font-family:\"Open Sans\"; text-transform:capitalize; border-top-width:0px; border-right-width:0px; border-bottom-width:0px; border-left-width:0px; border-color:#e5e5e5; border-style:solid}.eg-girovai2-element-18{font-size:15px; line-height:18px; color:#777777; font-weight:400; display:block; text-align:center; clear:none; margin:0px 0px 0px 0px ; padding:10px 20px 0px 20px ; border-radius:0px 0px 0px 0px ; background:transparent; position:relative; z-index:2 !important; font-family:\"Open Sans\"; text-transform:capitalize; border-top-width:0px; border-right-width:0px; border-bottom-width:0px; border-left-width:0px; border-color:#e5e5e5; border-style:solid}.eg-girovai2-element-9{font-size:21px !important; line-height:20px !important; color:#ffffff !important; font-weight:700 !important; padding:8px 80px 8px 80px !important; border-radius:3px 3px 0px 0px !important; background:#41a320 !important; z-index:2 !important; display:block; font-family:\"Open Sans\" !important; text-transform:uppercase !important}<\/style>\n<style type=\"text\/css\">.eg-girovai2-element-14:hover{font-size:16px !important; line-height:22px !important; color:#ffffff !important; font-weight:400 !important; border-radius:50px 50px 50px 50px !important; background:#54b948 !important; border-top-width:0px !important; border-right-width:0px !important; border-bottom-width:0px !important; border-left-width:0px !important; border-color:#ffffff !important; border-style:solid !important}.eg-girovai2-element-9:hover{font-size:21px !important; line-height:20px !important; color:#ffffff !important; font-weight:700 !important; border-radius:3px 3px 3px 3px !important; background:#0055a0 !important; font-family:\"Raleway\" !important; text-transform:uppercase !important}<\/style>\n<style type=\"text\/css\">.eg-girovai2-element-1-a{display:block; text-align:center; clear:both; margin:15px 20px 15px 20px ; position:relative}<\/style>\n<style type=\"text\/css\">.eg-girovai2-element-14-a{display:inline-block !important; float:none !important; clear:none !important; margin:0px 5px 0px 0px !important; position:relative !important}<\/style>\n<style type=\"text\/css\">.eg-girovai2-element-9-a{display:inline-block !important; float:none !important; clear:both !important; margin:15px 0px 0px 0px !important; position:relative !important}<\/style>\n<style type=\"text\/css\">.eg-girovai2-container{background:rgba(255,255,255,0.25)}<\/style>\n<style type=\"text\/css\">.eg-girovai2-content{background:#f5f5f5; padding:0px 0px 0px 0px; border-width:0px 0px 0px 0px; border-radius:0px 0px 0px 0px; border-color:transparent; border-style:none; text-align:center}<\/style>\n<style type=\"text\/css\">.esg-grid .mainul li.eg-girovai2-wrapper{background:#f5f5f5; padding:0px 0px 0px 0px; border-width:1px 1px 1px 1px; border-radius:0px 0px 0px 0px; border-color:#e5e5e5; border-style:solid}<\/style>\n<style type=\"text\/css\">.esg-grid .mainul li.eg-girovai2-wrapper .esg-media-poster{background-size:cover; background-position:center center; background-repeat:no-repeat}<\/style>\n<!-- THE ESSENTIAL GRID 2.3.6 POST -->\n\n<article class=\"myportfolio-container minimal-light source_type_post\" id=\"esg-grid-11-1-wrap\">\n\n    <div id=\"esg-grid-11-1\" class=\"esg-grid\" style=\"background: transparent;padding: 0px 0px 0px 0px ; box-sizing:border-box; -moz-box-sizing:border-box; -webkit-box-sizing:border-box; display:none\">\n<ul>\n<li id=\"eg-11-post-id-1952\" data-skin=\"girovai2\" class=\"filterall filter-antartide-it filter-programmi-in-offerta eg-girovai2-wrapper eg-post-id-1952\" data-date=\"1402580357\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img decoding=\"async\" src=\"https:\/\/girovai.com\/wp-content\/uploads\/2014\/06\/antartica10.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"600\" height=\"400\"><\/div>\n\n            <div class=\"esg-entry-cover\" data-clickable=\"on\">\n\n<a class=\"eg-invisiblebutton\" href=\"https:\/\/girovai.com\/it\/essential_grid\/antarctic-express-naviga-verso-sud-e-vola-verso-nord\/\" target=\"_self\"><\/a>                <div class=\"esg-overlay esg-transition eg-girovai2-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-fade\"><\/div>\n\n\t\t\t\t<div class=\"esg-bottom eg-post-1952 eg-girovai2-element-1-a\"><a class=\"eg-girovai2-element-1 eg-post-1952\" href=\"https:\/\/girovai.com\/it\/essential_grid\/antarctic-express-naviga-verso-sud-e-vola-verso-nord\/\" target=\"_self\">Antarctic Express: Naviga verso sud e vola verso nord<\/a><\/div>\n\t\t\t\t<div class=\"esg-center eg-post-1952 eg-girovai2-element-14-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-flipup\"><a class=\"eg-girovai2-element-14 eg-post-1952\" href=\"https:\/\/girovai.com\/it\/essential_grid\/antarctic-express-naviga-verso-sud-e-vola-verso-nord\/\" target=\"_self\"><i class=\"eg-icon-right-open\"><\/i><\/a><\/div>\n           <\/div>\n<div class=\"esg-entry-content eg-girovai2-content\">\n\t\t\t\t<div class=\"esg-content eg-post-1952 eg-girovai2-element-7\">Antarctica<\/div>\n\t\t\t\t<div class=\"esg-content eg-post-1952 eg-girovai2-element-19\">Crossings on Sale<\/div>\n\t\t\t\t<div class=\"esg-content eg-post-1952 eg-girovai2-element-17\">US$ 7.395\t\u20ac 5.620<\/div>\n\t\t\t\t<div class=\"esg-content eg-post-1952 eg-girovai2-element-18\">(10 Giorni \/ 9 Notti)<\/div>\n\t\t\t\t<div class=\"esg-content eg-post-1952 eg-girovai2-element-9-a\"><a class=\"eg-girovai2-element-9 eg-post-1952\" href=\"https:\/\/girovai.com\/it\/essential_grid\/antarctic-express-naviga-verso-sud-e-vola-verso-nord\/\" target=\"_self\"><i class=\"eg-icon-info-circled\"><\/i><\/a><\/div>\n<\/div>   <\/div>\n\n<\/li>\n<li id=\"eg-11-post-id-1946\" data-skin=\"girovai2\" class=\"filterall filter-antartide-it filter-pagina-inizialete-offerte-speciali filter-programmi-in-offerta eg-girovai2-wrapper eg-post-id-1946\" data-date=\"1402580430\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img decoding=\"async\" src=\"https:\/\/girovai.com\/wp-content\/uploads\/2014\/06\/antartica12.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"600\" height=\"400\"><\/div>\n\n            <div class=\"esg-entry-cover\" data-clickable=\"on\">\n\n<a class=\"eg-invisiblebutton\" href=\"https:\/\/girovai.com\/it\/essential_grid\/traversata-di-esplorazione-antartica\/\" target=\"_self\"><\/a>                <div class=\"esg-overlay esg-transition eg-girovai2-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-fade\"><\/div>\n\n\t\t\t\t<div class=\"esg-bottom eg-post-1946 eg-girovai2-element-1-a\"><a class=\"eg-girovai2-element-1 eg-post-1946\" href=\"https:\/\/girovai.com\/it\/essential_grid\/traversata-di-esplorazione-antartica\/\" target=\"_self\">Traversata di esplorazione Antartica<\/a><\/div>\n\t\t\t\t<div class=\"esg-center eg-post-1946 eg-girovai2-element-14-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-flipup\"><a class=\"eg-girovai2-element-14 eg-post-1946\" href=\"https:\/\/girovai.com\/it\/essential_grid\/traversata-di-esplorazione-antartica\/\" target=\"_self\"><i class=\"eg-icon-right-open\"><\/i><\/a><\/div>\n           <\/div>\n<div class=\"esg-entry-content eg-girovai2-content\">\n\t\t\t\t<div class=\"esg-content eg-post-1946 eg-girovai2-element-7\">Antarctica<\/div>\n\t\t\t\t<div class=\"esg-content eg-post-1946 eg-girovai2-element-19\">Crossings on Sale<\/div>\n\t\t\t\t<div class=\"esg-content eg-post-1946 eg-girovai2-element-17\">US$ 7.495\t\u20ac 5.696<\/div>\n\t\t\t\t<div class=\"esg-content eg-post-1946 eg-girovai2-element-18\">(12 Giorni \/ 11 Notti)<\/div>\n\t\t\t\t<div class=\"esg-content eg-post-1946 eg-girovai2-element-9-a\"><a class=\"eg-girovai2-element-9 eg-post-1946\" href=\"https:\/\/girovai.com\/it\/essential_grid\/traversata-di-esplorazione-antartica\/\" target=\"_self\"><i class=\"eg-icon-info-circled\"><\/i><\/a><\/div>\n<\/div>   <\/div>\n\n<\/li>\n<li id=\"eg-11-post-id-1943\" data-skin=\"girovai2\" class=\"filterall filter-antartide-it filter-programmi-in-offerta eg-girovai2-wrapper eg-post-id-1943\" data-date=\"1402580504\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img decoding=\"async\" src=\"https:\/\/girovai.com\/wp-content\/uploads\/2014\/06\/antartica14.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"600\" height=\"400\"><\/div>\n\n            <div class=\"esg-entry-cover\" data-clickable=\"on\">\n\n<a class=\"eg-invisiblebutton\" href=\"https:\/\/girovai.com\/it\/essential_grid\/traversata-del-circolo-polare-antartico\/\" target=\"_self\"><\/a>                <div class=\"esg-overlay esg-transition eg-girovai2-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-fade\"><\/div>\n\n\t\t\t\t<div class=\"esg-bottom eg-post-1943 eg-girovai2-element-1-a\"><a class=\"eg-girovai2-element-1 eg-post-1943\" href=\"https:\/\/girovai.com\/it\/essential_grid\/traversata-del-circolo-polare-antartico\/\" target=\"_self\">Traversata del circolo polare antartico<\/a><\/div>\n\t\t\t\t<div class=\"esg-center eg-post-1943 eg-girovai2-element-14-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-flipup\"><a class=\"eg-girovai2-element-14 eg-post-1943\" href=\"https:\/\/girovai.com\/it\/essential_grid\/traversata-del-circolo-polare-antartico\/\" target=\"_self\"><i class=\"eg-icon-right-open\"><\/i><\/a><\/div>\n           <\/div>\n<div class=\"esg-entry-content eg-girovai2-content\">\n\t\t\t\t<div class=\"esg-content eg-post-1943 eg-girovai2-element-7\">Antarctica<\/div>\n\t\t\t\t<div class=\"esg-content eg-post-1943 eg-girovai2-element-19\">Crossings on Sale<\/div>\n\t\t\t\t<div class=\"esg-content eg-post-1943 eg-girovai2-element-17\">US$ 6.995\t\u20ac 5.316<\/div>\n\t\t\t\t<div class=\"esg-content eg-post-1943 eg-girovai2-element-18\">(15 Giorni\/ 14 Notti)<\/div>\n\t\t\t\t<div class=\"esg-content eg-post-1943 eg-girovai2-element-9-a\"><a class=\"eg-girovai2-element-9 eg-post-1943\" href=\"https:\/\/girovai.com\/it\/essential_grid\/traversata-del-circolo-polare-antartico\/\" target=\"_self\"><i class=\"eg-icon-info-circled\"><\/i><\/a><\/div>\n<\/div>   <\/div>\n\n<\/li>\n<li id=\"eg-11-post-id-1934\" data-skin=\"girovai2\" class=\"filterall filter-antartide-it filter-programmi-in-offerta eg-girovai2-wrapper eg-post-id-1934\" data-date=\"1402580580\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img decoding=\"async\" src=\"https:\/\/girovai.com\/wp-content\/uploads\/2014\/06\/antartica05.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"600\" height=\"400\"><\/div>\n\n            <div class=\"esg-entry-cover\" data-clickable=\"on\">\n\n<a class=\"eg-invisiblebutton\" href=\"https:\/\/girovai.com\/it\/essential_grid\/introduzione-al-continente-bianco\/\" target=\"_self\"><\/a>                <div class=\"esg-overlay esg-transition eg-girovai2-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-fade\"><\/div>\n\n\t\t\t\t<div class=\"esg-bottom eg-post-1934 eg-girovai2-element-1-a\"><a class=\"eg-girovai2-element-1 eg-post-1934\" href=\"https:\/\/girovai.com\/it\/essential_grid\/introduzione-al-continente-bianco\/\" target=\"_self\">Introduzione al continente bianco<\/a><\/div>\n\t\t\t\t<div class=\"esg-center eg-post-1934 eg-girovai2-element-14-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-flipup\"><a class=\"eg-girovai2-element-14 eg-post-1934\" href=\"https:\/\/girovai.com\/it\/essential_grid\/introduzione-al-continente-bianco\/\" target=\"_self\"><i class=\"eg-icon-right-open\"><\/i><\/a><\/div>\n           <\/div>\n<div class=\"esg-entry-content eg-girovai2-content\">\n\t\t\t\t<div class=\"esg-content eg-post-1934 eg-girovai2-element-7\">Antarctica<\/div>\n\t\t\t\t<div class=\"esg-content eg-post-1934 eg-girovai2-element-19\">Crossings on Sale<\/div>\n\t\t\t\t<div class=\"esg-content eg-post-1934 eg-girovai2-element-17\">US$ 3.995 \/ \u20ac 3.036<\/div>\n\t\t\t\t<div class=\"esg-content eg-post-1934 eg-girovai2-element-18\">(10 giorni \/ 9 notti)<\/div>\n\t\t\t\t<div class=\"esg-content eg-post-1934 eg-girovai2-element-9-a\"><a class=\"eg-girovai2-element-9 eg-post-1934\" href=\"https:\/\/girovai.com\/it\/essential_grid\/introduzione-al-continente-bianco\/\" target=\"_self\"><i class=\"eg-icon-info-circled\"><\/i><\/a><\/div>\n<\/div>   <\/div>\n\n<\/li>\n<li id=\"eg-11-post-id-1921\" data-skin=\"girovai2\" class=\"filterall filter-antartide-it filter-programmi-in-offerta eg-girovai2-wrapper eg-post-id-1921\" data-date=\"1402580657\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img decoding=\"async\" src=\"https:\/\/girovai.com\/wp-content\/uploads\/2014\/06\/antartica06.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"600\" height=\"400\"><\/div>\n\n            <div class=\"esg-entry-cover\" data-clickable=\"on\">\n\n<a class=\"eg-invisiblebutton\" href=\"https:\/\/girovai.com\/it\/essential_grid\/isole-malvine-e-georgia-del-sud\/\" target=\"_self\"><\/a>                <div class=\"esg-overlay esg-transition eg-girovai2-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-fade\"><\/div>\n\n\t\t\t\t<div class=\"esg-bottom eg-post-1921 eg-girovai2-element-1-a\"><a class=\"eg-girovai2-element-1 eg-post-1921\" href=\"https:\/\/girovai.com\/it\/essential_grid\/isole-malvine-e-georgia-del-sud\/\" target=\"_self\">Isole Malvine e Georgia del Sud<\/a><\/div>\n\t\t\t\t<div class=\"esg-center eg-post-1921 eg-girovai2-element-14-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-flipup\"><a class=\"eg-girovai2-element-14 eg-post-1921\" href=\"https:\/\/girovai.com\/it\/essential_grid\/isole-malvine-e-georgia-del-sud\/\" target=\"_self\"><i class=\"eg-icon-right-open\"><\/i><\/a><\/div>\n           <\/div>\n<div class=\"esg-entry-content eg-girovai2-content\">\n\t\t\t\t<div class=\"esg-content eg-post-1921 eg-girovai2-element-7\">Antarctica<\/div>\n\t\t\t\t<div class=\"esg-content eg-post-1921 eg-girovai2-element-19\">Crossings on Sale<\/div>\n\t\t\t\t<div class=\"esg-content eg-post-1921 eg-girovai2-element-17\">$9.495 \/ \u20ac7.216<\/div>\n\t\t\t\t<div class=\"esg-content eg-post-1921 eg-girovai2-element-18\">20 Giorni \/ 19 Nottiar<\/div>\n\t\t\t\t<div class=\"esg-content eg-post-1921 eg-girovai2-element-9-a\"><a class=\"eg-girovai2-element-9 eg-post-1921\" href=\"https:\/\/girovai.com\/it\/essential_grid\/isole-malvine-e-georgia-del-sud\/\" target=\"_self\"><i class=\"eg-icon-info-circled\"><\/i><\/a><\/div>\n<\/div>   <\/div>\n\n<\/li>\n<\/ul>\n    <\/div>\n\n<\/article>\n<div class=\"clear\"><\/div>\n<script type=\"text\/javascript\">\nvar essapi_11;\njQuery(document).ready(function() {\n\tessapi_11 = jQuery(\"#esg-grid-11-1\").tpessential({\n        gridID:11,\n        layout:\"masonry\",\n        forceFullWidth:\"off\",\n        lazyLoad:\"off\",\n        row:3,\n\t\tapiName: \"essapi_11\",\n        loadMoreAjaxToken:\"a3d70c7bcb\",\n        loadMoreAjaxUrl:\"https:\/\/girovai.com\/wp-admin\/admin-ajax.php\",\n        loadMoreAjaxAction:\"Essential_Grid_Front_request_ajax\",\n        ajaxContentTarget:\"\",\n        ajaxScrollToOffset:\"0\",\n        ajaxCloseButton:\"off\",\n        ajaxContentSliding:\"on\",\n        ajaxScrollToOnLoad:\"on\",\n        ajaxCallbackArgument:\"on\",\n        ajaxNavButton:\"off\",\n        ajaxCloseType:\"button\",\n        ajaxCloseInner:\"false\",\n        ajaxCloseStyle:\"light\",\n        ajaxClosePosition:\"tr\",\n        space:10,\n        pageAnimation:\"fade\",\n        startAnimation: \"none\",\n        startAnimationSpeed: 1000,\n        startAnimationDelay: 100,\n        startAnimationType: \"item\",\n        animationType: \"item\",\n        paginationScrollToTop:\"off\",\n        paginationAutoplay:\"off\",\n        spinner:\"spinner3\",\n        spinnerColor:\"#FFFFFF\",\n        lightBoxMode:\"single\",\n\t\tlightboxHash:\"group\",\n\t\tlightboxPostMinWid:\"75%\",\n\t\tlightboxPostMaxWid:\"75%\",\n        lightboxSpinner:\"off\",\n        lightBoxFeaturedImg:\"off\",\n        lightBoxPostTitle:\"off\",\n        lightBoxPostTitleTag:\"h2\",\n\t\tlightboxMargin : \"0|0|0|0\",\n\t\tlbContentPadding : \"0|0|0|0\",\n\t\tlbContentOverflow : \"auto\",\n        animSpeed:1000,\n        delayBasic:1,\n        mainhoverdelay:1,\n        filterType:\"single\",\n        showDropFilter:\"hover\",\n        filterGroupClass:\"esg-fgc-11\",\n        filterNoMatch:\"No Items for the Selected Filter\",\n        filterDeepLink:\"off\",\n        hideMarkups: \"on\",\n        inViewport: true,\n        viewportBuffer: 20,\n        youtubeNoCookie:\"false\",\n        convertFilterMobile:false,\n        paginationSwipe: \"off\",\n        paginationDragVer: \"on\",\n        pageSwipeThrottle: 30,\n        googleFonts:['Open+Sans:300,400,600,700,800','Droid+Serif:400,700'],\n        hideBlankItemsAt: \"1\",\n        responsiveEntries: [\n\t\t\t\t\t\t{ width:1400,amount:3,mmheight:0},\n\t\t\t\t\t\t{ width:1170,amount:2,mmheight:0},\n\t\t\t\t\t\t{ width:1024,amount:1,mmheight:0},\n\t\t\t\t\t\t{ width:960,amount:2,mmheight:0},\n\t\t\t\t\t\t{ width:778,amount:1,mmheight:0},\n\t\t\t\t\t\t{ width:640,amount:1,mmheight:0},\n\t\t\t\t\t\t{ width:480,amount:1,mmheight:0}\n\t\t\t\t\t\t]\n\t});\n\n\tvar arrows = true,\n        lightboxOptions = {\n\t\tmargin : [0,0,0,0],\n\t\tbuttons : [\"share\",\"thumbs\",\"close\"],\n\t\tinfobar : true,\n\t\tloop : true,\n\t\tslideShow : {\"autoStart\": false, \"speed\": 3000},\n\t\tanimationEffect : \"fade\",\n\t\tanimationDuration : 500,\n\t\tbeforeShow: function(a, c) {\n          if(!arrows) {\n              jQuery(\"body\").addClass(\"esgbox-hidearrows\");\n          }\n\t\t\tvar i = 0,\n\t\t\t\tmultiple = false;\n\t\t\ta = a.slides;\n\t\t\tfor(var b in a) {\n\t\t\t\ti++;\n\t\t\t\tif(i > 1) {\n\t\t\t\t\tmultiple = true;\n\t\t\t\t\tbreak;\n\t\t\t\t}\n\t\t\t}\n\t\t\tif(!multiple) jQuery(\"body\").addClass(\"esgbox-single\");\n\t\t\tif(c.type === \"image\") jQuery(\".esgbox-button--zoom\").show();\n\t\t},\n\t\tbeforeLoad: function(a, b) {\n\t\t\tjQuery(\"body\").removeClass(\"esg-four-by-three\");\n\t\t\tif(b.opts.$orig.data(\"ratio\") === \"4:3\") jQuery(\"body\").addClass(\"esg-four-by-three\");\n\t\t},\n\t\tafterLoad: function() {jQuery(window).trigger(\"resize.esglb\");},\n\t\tafterClose : function() {jQuery(\"body\").removeClass(\"esgbox-hidearrows esgbox-single\");},\n\t\ttransitionEffect : \"fade\",\n\t\ttransitionDuration : 366,\n\t\thash : \"group\",\n\t\tarrows : true,\n\t\twheel : false,\n\t};\n\n\tjQuery(\"#esg-grid-11-1\").data(\"lightboxsettings\", lightboxOptions);\n\n\n});\n<\/script>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":2006,"menu_order":35,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2274","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/girovai.com\/it\/wp-json\/wp\/v2\/pages\/2274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/girovai.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/girovai.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/girovai.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/girovai.com\/it\/wp-json\/wp\/v2\/comments?post=2274"}],"version-history":[{"count":0,"href":"https:\/\/girovai.com\/it\/wp-json\/wp\/v2\/pages\/2274\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/girovai.com\/it\/wp-json\/wp\/v2\/pages\/2006"}],"wp:attachment":[{"href":"https:\/\/girovai.com\/it\/wp-json\/wp\/v2\/media?parent=2274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}